{"id":13434,"count":1,"description":"","link":"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/","name":"cbse datesheet class 10 2023","slug":"cbse-datesheet-class-10-2023","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>cbse datesheet class 10 2023 Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cbse datesheet class 10 2023 Archives -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/#website\",\"url\":\"https:\/\/www.searchurcollege.com\/blog\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.searchurcollege.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/#webpage\",\"url\":\"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/\",\"name\":\"cbse datesheet class 10 2023 Archives -\",\"isPartOf\":{\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.searchurcollege.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cbse datesheet class 10 2023\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cbse datesheet class 10 2023 Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/","og_locale":"en_US","og_type":"article","og_title":"cbse datesheet class 10 2023 Archives -","og_url":"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.searchurcollege.com\/blog\/#website","url":"https:\/\/www.searchurcollege.com\/blog\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.searchurcollege.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en"},{"@type":"CollectionPage","@id":"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/#webpage","url":"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/","name":"cbse datesheet class 10 2023 Archives -","isPartOf":{"@id":"https:\/\/www.searchurcollege.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.searchurcollege.com\/blog\/tag\/cbse-datesheet-class-10-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.searchurcollege.com\/blog\/"},{"@type":"ListItem","position":2,"name":"cbse datesheet class 10 2023"}]}]}},"_links":{"self":[{"href":"https:\/\/www.searchurcollege.com\/blog\/wp-json\/wp\/v2\/tags\/13434"}],"collection":[{"href":"https:\/\/www.searchurcollege.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.searchurcollege.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.searchurcollege.com\/blog\/wp-json\/wp\/v2\/posts?tags=13434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}