{"id":23610,"count":1,"description":"","link":"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/","name":"World university of design sonepat fees structure","slug":"world-university-of-design-sonepat-fees-structure","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>World university of design sonepat fees structure Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"World university of design sonepat fees structure Archives -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/#website\",\"url\":\"https:\/\/www.searchurcollege.com\/blog\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.searchurcollege.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/#webpage\",\"url\":\"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/\",\"name\":\"World university of design sonepat fees structure Archives -\",\"isPartOf\":{\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.searchurcollege.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"World university of design sonepat fees structure\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"World university of design sonepat fees structure Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/","og_locale":"en_US","og_type":"article","og_title":"World university of design sonepat fees structure Archives -","og_url":"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.searchurcollege.com\/blog\/#website","url":"https:\/\/www.searchurcollege.com\/blog\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.searchurcollege.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en"},{"@type":"CollectionPage","@id":"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/#webpage","url":"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/","name":"World university of design sonepat fees structure Archives -","isPartOf":{"@id":"https:\/\/www.searchurcollege.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.searchurcollege.com\/blog\/tag\/world-university-of-design-sonepat-fees-structure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.searchurcollege.com\/blog\/"},{"@type":"ListItem","position":2,"name":"World university of design sonepat fees structure"}]}]}},"_links":{"self":[{"href":"https:\/\/www.searchurcollege.com\/blog\/wp-json\/wp\/v2\/tags\/23610"}],"collection":[{"href":"https:\/\/www.searchurcollege.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.searchurcollege.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.searchurcollege.com\/blog\/wp-json\/wp\/v2\/posts?tags=23610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}